{"id":4161,"date":"2025-11-24T14:55:41","date_gmt":"2025-11-24T12:55:41","guid":{"rendered":"https:\/\/gap.espace-gold-change.com\/?page_id=4161"},"modified":"2025-11-24T15:00:08","modified_gmt":"2025-11-24T13:00:08","slug":"important-tax-information","status":"publish","type":"page","link":"https:\/\/gap.espace-gold-change.com\/en\/informations-fiscales-importantes\/","title":{"rendered":"Important tax information"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4161\" class=\"elementor elementor-4161\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6a517fd0 e-flex e-con-boxed e-con e-parent\" data-id=\"6a517fd0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a070756 elementor-widget elementor-widget-heading\" data-id=\"7a070756\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Informations fiscales importantes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1013ab6f e-flex e-con-boxed e-con e-parent\" data-id=\"1013ab6f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-68daee0e elementor-widget elementor-widget-heading\" data-id=\"68daee0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ESPACE GOLD CHANGE <br>VOUS INFOMRE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50cd5e8c elementor-widget elementor-widget-spacer\" data-id=\"50cd5e8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-35ae88 e-flex e-con-boxed e-con e-parent\" data-id=\"35ae88\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7d9d75ec e-con-full e-flex e-con e-child\" data-id=\"7d9d75ec\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-326d9d61 elementor-position-inline-start elementor-mobile-position-inline-start elementor-widget-widescreen__width-initial elementor-widget-mobile__width-initial elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"326d9d61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tFiscalit\u00e9 sur les m\u00e9taux pr\u00e9cieux\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-39205c68 e-con-full e-flex e-con e-child\" data-id=\"39205c68\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5398073a elementor-widget-mobile__width-initial elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5398073a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-66cf0b3b e-flex e-con-boxed e-con e-parent\" data-id=\"66cf0b3b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-63cc31f5 e-con-full e-flex e-con e-child\" data-id=\"63cc31f5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-10adef53 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"10adef53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">La vente d\u2019or, d\u2019argent, de bijoux, de montres ou d\u2019objets de collection est soumise \u00e0 une fiscalit\u00e9 sp\u00e9cifique pr\u00e9vue par le Code g\u00e9n\u00e9ral des imp\u00f4ts (articles 150 VI \u00e0 150 VM).<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:315}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Deux r\u00e9gimes existent selon la situation du vendeur :<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:315}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4750c069 elementor-widget__width-initial elementor-widget-mobile_extra__width-inherit elementor-widget elementor-widget-heading\" data-id=\"4750c069\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">LA TMP : TAXE SUR LES M\u00c9TAUX PR\u00c9CIEUX<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5aff6a15 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"5aff6a15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b><span data-contrast=\"auto\">Principe<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:270}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">La TMP est une taxe forfaitaire pr\u00e9lev\u00e9e sur le prix total de vente, quel que soit le b\u00e9n\u00e9fice r\u00e9alis\u00e9.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:270}\"> \u00a0<\/span><span data-contrast=\"auto\">Elle s\u2019applique automatiquement, sauf si le vendeur choisit d\u2019opter pour le r\u00e9gime de la plus-value r\u00e9elle.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:270}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:270}\">\u00a0<\/span><\/p><p><b><span data-contrast=\"auto\">Taux en vigueur<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:270}\">\u00a0<\/span><\/p><ul><li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"1\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">11 % pour les m\u00e9taux pr\u00e9cieux <\/span><span data-contrast=\"auto\">(or, argent, platine, lingots, pi\u00e8ces, etc.).<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:0,&quot;335559739&quot;:0}\">\u00a0<\/span><\/li><\/ul><ul><li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"2\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">6 % pour les bijoux, objets d\u2019art, de collection ou d\u2019antiquit\u00e9.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:0,&quot;335559739&quot;:0}\">\u00a0<\/span><\/li><\/ul><p><span data-contrast=\"auto\">Auquel s\u2019ajoute la CRDS s\u2019\u00e9levant \u00e0 0,5%.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:270}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:270}\">\u00a0<\/span><\/p><p><b><span data-contrast=\"auto\">Qui paie cette taxe ?<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:270}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">La taxe est pr\u00e9lev\u00e9e au moment de la vente et <\/span><b><span data-contrast=\"auto\">directement r\u00e9gl\u00e9e par Espace Gold Change<\/span><\/b><span data-contrast=\"auto\"> aupr\u00e8s de l\u2019administration fiscale, vous garantissant une transaction simple, nette et sans formalit\u00e9 suppl\u00e9mentaire.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:270}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7068e923 elementor-widget__width-initial elementor-widget-mobile_extra__width-inherit elementor-widget elementor-widget-heading\" data-id=\"7068e923\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">LA TPV : TAXE SUR LA PLUS-VALUE R\u00c9ELLE<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c924bb elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"4c924bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b><span data-contrast=\"auto\">Principe<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:270}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">La TPV est une alternative \u00e0 la TMP.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:270}\">\u00a0<\/span><span data-contrast=\"auto\">Elle ne s\u2019applique que si le vendeur peut prouver le prix et la date d\u2019acquisition du bien (facture, acte de succession, certificat d\u2019achat, etc.).<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:270}\">\u00a0<\/span><span data-contrast=\"auto\">Dans ce cas, la taxation ne porte pas sur le prix total de vente, mais uniquement sur le b\u00e9n\u00e9fice r\u00e9ellement r\u00e9alis\u00e9 :<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:270}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Plus-value = Prix de vente \u2013 Prix d\u2019achat<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:270}\">\u00a0<\/span><\/p><p><b><span data-contrast=\"auto\">Taux de la TPV<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:270}\">\u00a0<\/span><\/p><ul><li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"3\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">19 % d\u2019imp\u00f4t sur le revenu<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:0,&quot;335559739&quot;:0}\">\u00a0<\/span><\/li><\/ul><ul><li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"3\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"auto\">17,2 % de pr\u00e9l\u00e8vements sociaux<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:0,&quot;335559739&quot;:0}\">\u00a0<\/span><\/li><\/ul><p><span data-contrast=\"auto\">Soit 36,2 % sur la plus-value nette, apr\u00e8s abattement selon la dur\u00e9e de d\u00e9tention.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:270}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:270}\">\u00a0<\/span><\/p><p><b><span data-contrast=\"auto\">Abattement progressif<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:270}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">La loi pr\u00e9voit une r\u00e9duction progressive selon la dur\u00e9e de d\u00e9tention :<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:270}\">\u00a0<\/span><\/p><ul><li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"4\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Moins de 2 ans : 0% d\u2019abattement<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:0,&quot;335559739&quot;:0}\">\u00a0<\/span><\/li><\/ul><ul><li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"4\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"auto\">De 3 \u00e0 22 ans : 5 % par ann\u00e9e de d\u00e9tention<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:0,&quot;335559739&quot;:0}\">\u00a0<\/span><\/li><\/ul><ul><li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"4\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"3\" data-aria-level=\"1\"><span data-contrast=\"auto\">Au-del\u00e0 de 22 ans : 100 % d\u2019exon\u00e9ration<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:0,&quot;335559739&quot;:0}\">\u00a0<\/span><\/li><\/ul><p><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:0,&quot;335559739&quot;:0}\">\u00a0<\/span><\/p><p><b><span data-contrast=\"auto\">Qui paie cette taxe ?<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:270}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">La taxe est <\/span><b><span data-contrast=\"auto\">d\u00e9clar\u00e9e et pay\u00e9e par le vendeur<\/span><\/b><span data-contrast=\"auto\"> dans le mois suivant la cession, via le formulaire officiel n\u00b02092, avec la possibilit\u00e9 d\u2019\u00eatre accompagn\u00e9 par Espace Gold Change pour simplifier les d\u00e9marches.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:270}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6878c524 elementor-widget__width-initial elementor-widget-mobile_extra__width-inherit elementor-widget elementor-widget-heading\" data-id=\"6878c524\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">FISCALIT\u00c9 SUR LA DONATION <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36d77f1c elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"36d77f1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">Lorsqu\u2019un bien pr\u00e9cieux, comme une pi\u00e8ce d\u2019or, est transmis sans contrepartie, il entre dans le cadre des droits de mutation \u00e0 titre gratuit d\u00e9finis par les articles 790 E et 790 F du Code g\u00e9n\u00e9ral des imp\u00f4ts.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:330}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Ces transmissions peuvent toutefois b\u00e9n\u00e9ficier d\u2019abattements ou d\u2019exon\u00e9rations selon le lien familial.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:330}\">\u00a0<\/span><\/p><ul><li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"5\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Enfants et donataires handicap\u00e9s (sous conditions) : 100 000 \u20ac<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:0,&quot;335559739&quot;:0}\">\u00a0<\/span><\/li><\/ul><ul><li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"5\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"auto\">Entre \u00e9poux ou partenaires de PACS : 80 724 \u20ac<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:0,&quot;335559739&quot;:0}\">\u00a0<\/span><\/li><\/ul><ul><li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"5\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"3\" data-aria-level=\"1\"><span data-contrast=\"auto\">Fr\u00e8res et s\u0153urs : 15 932 \u20ac<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:0,&quot;335559739&quot;:0}\">\u00a0<\/span><\/li><\/ul><ul><li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"5\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"4\" data-aria-level=\"1\"><span data-contrast=\"auto\">Petits-enfants : 31 865 \u20ac<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:0,&quot;335559739&quot;:0}\">\u00a0<\/span><\/li><\/ul><ul><li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"5\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"5\" data-aria-level=\"1\"><span data-contrast=\"auto\">Neveux et ni\u00e8ces : 7 967 \u20ac<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:0,&quot;335559739&quot;:0}\">\u00a0<\/span><\/li><\/ul><ul><li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"5\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"6\" data-aria-level=\"1\"><span data-contrast=\"auto\">Arri\u00e8re-petits-enfants : 5 310 \u20ac<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:0,&quot;335559739&quot;:0}\">\u00a0<\/span><\/li><\/ul><p><span data-contrast=\"auto\">Les concubins non mari\u00e9s ou personnes sans lien de parent\u00e9 ne b\u00e9n\u00e9ficient d\u2019aucun abattement. Une taxation forfaitaire de 60 % s\u2019applique sur la valeur totale des biens.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:270}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e56cec2 elementor-widget elementor-widget-spacer\" data-id=\"2e56cec2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-54c4bef9 e-flex e-con-boxed e-con e-parent\" data-id=\"54c4bef9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8246be4 elementor-widget elementor-widget-spacer\" data-id=\"8246be4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3fc1809b e-flex e-con-boxed e-con e-parent\" data-id=\"3fc1809b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5039a7c8 e-con-full e-flex e-con e-child\" data-id=\"5039a7c8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6938fd5a elementor-position-inline-start elementor-mobile-position-inline-start elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"6938fd5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tModalit\u00e9 de tarif de rachat de bijoux non destin\u00e9s \u00e0 la fonte et autres biens\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6644b6c4 e-con-full e-flex e-con e-child\" data-id=\"6644b6c4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-21c1fcc8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"21c1fcc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-75f2fbc5 e-flex e-con-boxed e-con e-parent\" data-id=\"75f2fbc5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-463f63c5 e-con-full e-flex e-con e-child\" data-id=\"463f63c5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3f420945 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"3f420945\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"TextRun MacChromeBold SCXW149254411 BCX0\" lang=\"FR-FR\" xml:lang=\"FR-FR\" data-contrast=\"auto\"><span class=\"NormalTextRun ContextualSpellingAndGrammarErrorV2Themed SCXW149254411 BCX0\">Conform\u00e9ment<\/span><span class=\"NormalTextRun SCXW149254411 BCX0\"> \u00e0 l\u2019article 4 de l\u2019arr\u00eat\u00e9 du 18 ao\u00fbt 2015<\/span><\/span><span class=\"EOP SCXW149254411 BCX0\" data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559740&quot;:390}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-310fd824 elementor-widget__width-initial elementor-widget-mobile_extra__width-inherit elementor-widget elementor-widget-heading\" data-id=\"310fd824\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">1. PROC\u00c9DURE D\u2019\u00c9VALUATION <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22c08750 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"22c08750\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">L\u2019\u00e9valuation est effectu\u00e9e par un <\/span><b><span data-contrast=\"auto\">acheteur-\u00e9valuateur mandat\u00e9 <\/span><\/b><span data-contrast=\"auto\">par la soci\u00e9t\u00e9 <\/span><b><span data-contrast=\"auto\">ESPACE GOLD CHANGE<\/span><\/b><span data-contrast=\"auto\">, conform\u00e9ment \u00e0 la r\u00e9glementation relative \u00e0 l\u2019information du consommateur sur les prix d\u2019achat des m\u00e9taux pr\u00e9cieux.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:270}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Si n\u00e9cessaire, la soci\u00e9t\u00e9 peut faire appel \u00e0 des experts externes pour affiner l\u2019estimation. Celle-ci est toujours r\u00e9alis\u00e9e avant de proposer au consommateur-vendeur un prix d\u2019achat global, pr\u00e9sent\u00e9 dans le contrat sous la forme d\u2019une offre ferme et d\u00e9finitive.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:270}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23932418 elementor-widget__width-initial elementor-widget-mobile_extra__width-inherit elementor-widget elementor-widget-heading\" data-id=\"23932418\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2. CRIT\u00c8RES D\u2019\u00c9VALUATION <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29e806ee elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"29e806ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">Les objets propos\u00e9s \u00e0 l\u2019achat font l\u2019objet d\u2019une <\/span><b><span data-contrast=\"auto\">expertise personnalis\u00e9e<\/span><\/b><span data-contrast=\"auto\"> r\u00e9alis\u00e9e par la soci\u00e9t\u00e9, prenant en compte plusieurs param\u00e8tres notamment :<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:270}\">\u00a0<\/span><\/p><ul><li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"6\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">La <\/span><b><span data-contrast=\"auto\">marque<\/span><\/b><span data-contrast=\"auto\">, le <\/span><b><span data-contrast=\"auto\">mod\u00e8le<\/span><\/b><span data-contrast=\"auto\"> et la <\/span><b><span data-contrast=\"auto\">raret\u00e9<\/span><\/b><span data-contrast=\"auto\"> de l\u2019objet ;<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:0,&quot;335559739&quot;:0}\">\u00a0<\/span><\/li><\/ul><ul><li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"6\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"auto\">Son <\/span><b><span data-contrast=\"auto\">\u00e9tat<\/span><\/b> <b><span data-contrast=\"auto\">g\u00e9n\u00e9ral<\/span><\/b><span data-contrast=\"auto\">, ainsi que les \u00e9ventuelles restaurations ou r\u00e9parations \u00e0 pr\u00e9voir ;<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:0,&quot;335559739&quot;:0}\">\u00a0<\/span><\/li><\/ul><ul><li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"6\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"3\" data-aria-level=\"1\"><span data-contrast=\"auto\">L\u2019<\/span><b><span data-contrast=\"auto\">anciennet\u00e9<\/span><\/b><span data-contrast=\"auto\"> et la <\/span><b><span data-contrast=\"auto\">nature des mat\u00e9riaux <\/span><\/b><span data-contrast=\"auto\">(m\u00e9taux pr\u00e9cieux, pierres fines ou pr\u00e9cieuses, gravures, etc.) ;<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:0,&quot;335559739&quot;:0}\">\u00a0<\/span><\/li><\/ul><ul><li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"6\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"4\" data-aria-level=\"1\"><span data-contrast=\"auto\">La <\/span><b><span data-contrast=\"auto\">pr\u00e9sence d\u2019\u00e9l\u00e9ments compl\u00e9mentaires<\/span><\/b><span data-contrast=\"auto\"> tels que la bo\u00eete d\u2019origine, la facture, le carnet d\u2019entretien ou carte d\u2019authenticit\u00e9 ;<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:0,&quot;335559739&quot;:0}\">\u00a0<\/span><\/li><\/ul><ul><li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"6\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"5\" data-aria-level=\"1\"><span data-contrast=\"auto\">La <\/span><b><span data-contrast=\"auto\">valeur de revente sur le march\u00e9 de seconde main<\/span><\/b><span data-contrast=\"auto\">, certains mod\u00e8les b\u00e9n\u00e9ficiant d\u2019une demande accrue influant sur l\u2019offre de rachat.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:0,&quot;335559739&quot;:0}\">\u00a0<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13f4aec4 elementor-widget__width-initial elementor-widget-mobile_extra__width-inherit elementor-widget elementor-widget-heading\" data-id=\"13f4aec4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3. AUTENTICIT\u00c9 ET R\u00c9SERVE <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7cc4fe95 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"7cc4fe95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"TextRun SCXW153350755 BCX0\" lang=\"FR-FR\" xml:lang=\"FR-FR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW153350755 BCX0\">En cas de doute concernant l\u2019authenticit\u00e9, la provenance ou la qualit\u00e9 d\u2019un objet, la soci\u00e9t\u00e9 se r\u00e9serve le droit de refuser l\u2019achat imm\u00e9diat et de proposer un <\/span><\/span><span class=\"TextRun MacChromeBold SCXW153350755 BCX0\" lang=\"FR-FR\" xml:lang=\"FR-FR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW153350755 BCX0\">contrat de d\u00e9p\u00f4t-confi\u00e9.<\/span><\/span><span class=\"EOP SCXW153350755 BCX0\" data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:270}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51f759fc elementor-widget__width-initial elementor-widget-mobile_extra__width-inherit elementor-widget elementor-widget-heading\" data-id=\"51f759fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">4. CONTRAT DE D\u00c9P\u00d4T-CONFI\u00c9 <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6521d7a8 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"6521d7a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">Dans ce cadre :<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:270}\">\u00a0<\/span><\/p><ul><li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"7\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">L\u2019objet est confi\u00e9 temporairement \u00e0 la soci\u00e9t\u00e9 pour un examen approfondi dans ses locaux ;<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:0,&quot;335559739&quot;:0}\">\u00a0<\/span><\/li><\/ul><ul><li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"7\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"auto\">\u00c0 l\u2019issue de l\u2019expertise, une proposition de rachat est transmise au d\u00e9posant ;<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:0,&quot;335559739&quot;:0}\">\u00a0<\/span><\/li><\/ul><ul><li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"7\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"3\" data-aria-level=\"1\"><span data-contrast=\"auto\">En cas de refus, l\u2019objet est restitu\u00e9 dans l\u2019\u00e9tat dans lequel il a \u00e9t\u00e9 confi\u00e9, aux frais de l\u2019entreprise.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:0,&quot;335559739&quot;:0}\">\u00a0<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7724dea9 elementor-widget__width-initial elementor-widget-mobile_extra__width-inherit elementor-widget elementor-widget-heading\" data-id=\"7724dea9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">5. LIMITATION DE RESPONSABILIT\u00c9 <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e482903 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"4e482903\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"TextRun SCXW104360449 BCX0\" lang=\"FR-FR\" xml:lang=\"FR-FR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW104360449 BCX0\">La soci\u00e9t\u00e9 n\u2019est tenue qu\u2019\u00e0 une obligation de moyens dans le cadre de l\u2019expertise. Elle ne saurait \u00eatre tenue responsable en cas de contestation ult\u00e9rieure relative \u00e0 la valeur estim\u00e9e ou \u00e0 la fluctuation des prix du march\u00e9 de seconde main.<\/span><\/span><span class=\"EOP SCXW104360449 BCX0\" data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:270}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-10dcb709 e-flex e-con-boxed e-con e-parent\" data-id=\"10dcb709\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c761588 elementor-widget elementor-widget-spacer\" data-id=\"c761588\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-70f3ac35 e-flex e-con-boxed e-con e-parent\" data-id=\"70f3ac35\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2854f693 e-con-full e-flex e-con e-child\" data-id=\"2854f693\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c8c59a3 elementor-widget elementor-widget-spacer\" data-id=\"6c8c59a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5436f077 e-flex e-con-boxed e-con e-parent\" data-id=\"5436f077\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4f5d3d89 e-con-full e-flex e-con e-child\" data-id=\"4f5d3d89\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-735034c9 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"735034c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tLes poin\u00e7ons\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e1f6858 e-con-full e-flex e-con e-child\" data-id=\"e1f6858\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-46f2f0ef elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"46f2f0ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1f39c94a e-flex e-con-boxed e-con e-parent\" data-id=\"1f39c94a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6031c992 e-con-full e-flex e-con e-child\" data-id=\"6031c992\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2cd76517 elementor-widget elementor-widget-image\" data-id=\"2cd76517\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"779\" height=\"1024\" src=\"https:\/\/gap.espace-gold-change.com\/wp-content\/uploads\/sites\/49\/2025\/11\/Garantie-des-metaux-precieux-779x1024.png\" class=\"attachment-large size-large wp-image-4164\" alt=\"\" srcset=\"https:\/\/gap.espace-gold-change.com\/wp-content\/uploads\/sites\/49\/2025\/11\/Garantie-des-metaux-precieux-779x1024.png 779w, https:\/\/gap.espace-gold-change.com\/wp-content\/uploads\/sites\/49\/2025\/11\/Garantie-des-metaux-precieux-228x300.png 228w, https:\/\/gap.espace-gold-change.com\/wp-content\/uploads\/sites\/49\/2025\/11\/Garantie-des-metaux-precieux-768x1009.png 768w, https:\/\/gap.espace-gold-change.com\/wp-content\/uploads\/sites\/49\/2025\/11\/Garantie-des-metaux-precieux-1169x1536.png 1169w, https:\/\/gap.espace-gold-change.com\/wp-content\/uploads\/sites\/49\/2025\/11\/Garantie-des-metaux-precieux-9x12.png 9w, https:\/\/gap.espace-gold-change.com\/wp-content\/uploads\/sites\/49\/2025\/11\/Garantie-des-metaux-precieux.png 1326w\" sizes=\"(max-width: 779px) 100vw, 779px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-211e3e8b elementor-widget elementor-widget-spacer\" data-id=\"211e3e8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6318dc2d e-flex e-con-boxed e-con e-parent\" data-id=\"6318dc2d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-37be832a elementor-widget elementor-widget-spacer\" data-id=\"37be832a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-40eebe52 e-flex e-con-boxed e-con e-parent\" data-id=\"40eebe52\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-65f259e7 e-con-full e-flex e-con e-child\" data-id=\"65f259e7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7931be9a elementor-position-inline-start elementor-mobile-position-inline-start elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"7931be9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tTaxe sur les m\u00e9taux pr\u00e9cieux, les bijoux, les objets d'art, de collection et d'antiquit\u00e9 \t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-71069b67 e-con-full e-flex e-con e-child\" data-id=\"71069b67\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55ac969b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"55ac969b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3b8adf61 e-flex e-con-boxed e-con e-parent\" data-id=\"3b8adf61\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4a87351b e-con-full e-flex e-con e-child\" data-id=\"4a87351b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-75e1d558 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"75e1d558\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">LA TAXE SUR LES M\u00c9TAUX PR\u00c9CIEUX EST ENTI\u00c8REEMENT R\u00c9GL\u00c9E PAR NOS SOINS SELON LES CONDITIONS PR\u00c9VUES AUX ARTICLES 150 VJ \u00c0 150 VM<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-581f686c elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"581f686c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b><span data-contrast=\"auto\">ARTICLE 150 VI<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:660}\">\u00a0<\/span><\/p><p><span style=\"background-color: transparent; font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, 'Helvetica Neue', Arial, 'Noto Sans', sans-serif, 'Apple Color Emoji', 'Segoe UI Emoji', 'Segoe UI Symbol', 'Noto Color Emoji';\" data-contrast=\"auto\">I. Sous r\u00e9serve des dispositions propres aux b\u00e9n\u00e9fices professionnels, sont soumises \u00e0 une taxe forfaitaire dans les conditions pr\u00e9vues aux <\/span><a style=\"font-family: -apple-system, BlinkMacSystemFont, &#039;Segoe UI&#039;, Roboto, &#039;Helvetica Neue&#039;, Arial, &#039;Noto Sans&#039;, sans-serif, &#039;Apple Color Emoji&#039;, &#039;Segoe UI Emoji&#039;, &#039;Segoe UI Symbol&#039;, &#039;Noto Color Emoji&#039;;\" href=\"https:\/\/www.legifrance.gouv.fr\/affichCodeArticle.do?cidTexte=LEGITEXT000006069577&amp;idArticle=LEGIARTI000006302814&amp;dateTexte=&amp;categorieLien=cid\" rel=\"noopener\"><span data-contrast=\"none\">articles 150 VJ \u00e0 150 VM<\/span><\/a><span style=\"background-color: transparent; font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, 'Helvetica Neue', Arial, 'Noto Sans', sans-serif, 'Apple Color Emoji', 'Segoe UI Emoji', 'Segoe UI Symbol', 'Noto Color Emoji';\" data-contrast=\"auto\"> les cessions \u00e0 titre on\u00e9reux ou les exportations, autres que temporaires, hors du territoire des Etats membres de l&rsquo;Union europ\u00e9enne :<\/span><\/p><p><span data-contrast=\"auto\">1\u00b0 De m\u00e9taux pr\u00e9cieux ;<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:660}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">2\u00b0 De bijoux, d&rsquo;objets d&rsquo;art, de collection ou d&rsquo;antiquit\u00e9.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:660}\">\u00a0<\/span><\/p><p><span style=\"background-color: transparent; font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, 'Helvetica Neue', Arial, 'Noto Sans', sans-serif, 'Apple Color Emoji', 'Segoe UI Emoji', 'Segoe UI Symbol', 'Noto Color Emoji';\">II. (Abrog\u00e9)<\/span><\/p><p><span data-contrast=\"auto\">Loi n\u00b0 2013-1278 du 29 d\u00e9cembre 2013 de finances pour 2014, art. 19 III : Ces dispositions s&rsquo;appliquent aux cessions et aux exportations de biens r\u00e9alis\u00e9es \u00e0 compter du 1er janvier 2014.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:660}\">\u00a0<\/span><\/p><p><b><span data-contrast=\"auto\">ARTICLE 150 VJ<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:660}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Sont exon\u00e9r\u00e9es de la taxe :<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:660}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">1\u00b0 Les cessions r\u00e9alis\u00e9es au profit d&rsquo;un mus\u00e9e auquel a \u00e9t\u00e9 attribu\u00e9e l&rsquo;appellation \u00a0\u00bb mus\u00e9e de France \u00a0\u00bb pr\u00e9vue \u00e0 l&rsquo;article <\/span><a href=\"https:\/\/www.legifrance.gouv.fr\/affichCodeArticle.do?cidTexte=LEGITEXT000006074236&amp;idArticle=LEGIARTI000006845650&amp;dateTexte=&amp;categorieLien=cid\" rel=\"noopener\"><span data-contrast=\"none\">L. 441-1 <\/span><\/a><span data-contrast=\"auto\">du code du patrimoine ou d&rsquo;un mus\u00e9e d&rsquo;une collectivit\u00e9 territoriale ;<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:660}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">2\u00b0 Les cessions r\u00e9alis\u00e9es au profit de la Biblioth\u00e8que nationale de France ou d&rsquo;une autre biblioth\u00e8que de l&rsquo;Etat, d&rsquo;une collectivit\u00e9 territoriale ou d&rsquo;une autre personne publique ;<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:660}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">3\u00b0 Les cessions r\u00e9alis\u00e9es au profit d&rsquo;un service d&rsquo;archives de l&rsquo;Etat, d&rsquo;une collectivit\u00e9 territoriale ou d&rsquo;une autre personne publique ;<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:660}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">4\u00b0 Les cessions ou les exportations des biens mentionn\u00e9s au 2\u00b0 du I de <\/span><a href=\"https:\/\/www.legifrance.gouv.fr\/affichCodeArticle.do?cidTexte=LEGITEXT000006069577&amp;idArticle=LEGIARTI000006302813&amp;dateTexte=&amp;categorieLien=cid\" rel=\"noopener\"><span data-contrast=\"none\">l&rsquo;article 150 VI<\/span><\/a><span data-contrast=\"auto\"> lorsque le prix de cession ou la valeur en douane n&rsquo;exc\u00e8de pas 5 000 \u20ac ;<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:660}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">5\u00b0 Les cessions ou les exportations de biens mentionn\u00e9s au I de l&rsquo;article 150 VI, lorsque le c\u00e9dant ou l&rsquo;exportateur n&rsquo;a pas en France son domicile fiscal. L&rsquo;exportateur doit pouvoir justifier d&rsquo;une importation ant\u00e9rieure, d&rsquo;une introduction ant\u00e9rieure ou d&rsquo;une acquisition en France ;<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:660}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">6\u00b0 Abrog\u00e9.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:660}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Loi n\u00b0 2013-1278 du 29 d\u00e9cembre 2013 de finances pour 2014, art. 19 III : Ces dispositions s&rsquo;appliquent aux cessions et aux exportations de biens r\u00e9alis\u00e9es \u00e0 compter du 1er janvier 2014.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:660}\">\u00a0<\/span><\/p><p><b><span data-contrast=\"auto\">ARTICLE 150 VK<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:660}\">\u00a0<\/span><\/p><p><span style=\"background-color: transparent; font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, 'Helvetica Neue', Arial, 'Noto Sans', sans-serif, 'Apple Color Emoji', 'Segoe UI Emoji', 'Segoe UI Symbol', 'Noto Color Emoji';\">I. La taxe est support\u00e9e par le vendeur ou l&rsquo;exportateur. Elle est due, sous leur responsabilit\u00e9, par l&rsquo;interm\u00e9diaire \u00e9tabli fiscalement en France participant \u00e0 la transaction ou, en l&rsquo;absence d&rsquo;interm\u00e9diaire, par l&rsquo;acqu\u00e9reur lorsque celui-ci\u00a0<\/span><\/p><p><span data-contrast=\"auto\">est un assujetti \u00e0 la taxe sur la valeur ajout\u00e9e \u00e9tabli en France ; dans les autres cas, elle est due par le vendeur ou l&rsquo;exportateur.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:660}\">\u00a0<\/span><\/p><p><span style=\"background-color: transparent; font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, 'Helvetica Neue', Arial, 'Noto Sans', sans-serif, 'Apple Color Emoji', 'Segoe UI Emoji', 'Segoe UI Symbol', 'Noto Color Emoji';\">II. La taxe est \u00e9gale :<\/span><\/p><p><span data-contrast=\"auto\">1\u00b0 <\/span><span data-contrast=\"auto\">A 11 % du prix de cession<\/span><span data-contrast=\"auto\"> ou de la valeur en douane des biens mentionn\u00e9s au 1\u00b0 du I de <\/span><a href=\"https:\/\/www.legifrance.gouv.fr\/affichCodeArticle.do?cidTexte=LEGITEXT000006069577&amp;idArticle=LEGIARTI000006302813&amp;dateTexte=&amp;categorieLien=cid\" rel=\"noopener\"><span data-contrast=\"none\">l&rsquo;article 150 VI<\/span><\/a><span data-contrast=\"auto\"> ;<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:660}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">2\u00b0 <\/span><span data-contrast=\"auto\">A 6 % du prix de cession<\/span><span data-contrast=\"auto\"> ou de la valeur en douane des biens mentionn\u00e9s au 2\u00b0 du I de l&rsquo;article 150 VI.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:660}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">III. \u2013 La taxe est exigible au moment de la cession ou de l&rsquo;exportation.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:660}\">\u00a0<\/span><\/p><p><b><span data-contrast=\"auto\">ARTICLE 150 VL<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:660}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Le vendeur ou l&rsquo;exportateur peut opter pour le r\u00e9gime d\u00e9fini \u00e0 <\/span><a href=\"https:\/\/www.legifrance.gouv.fr\/affichCodeArticle.do?cidTexte=LEGITEXT000006069577&amp;idArticle=LEGIARTI000006302768&amp;dateTexte=&amp;categorieLien=cid\" rel=\"noopener\"><span data-contrast=\"none\">l&rsquo;article 150 UA <\/span><\/a><span data-contrast=\"auto\">\u00e0 la condition de justifier de la date et du prix d&rsquo;acquisition du bien ou de justifier que le bien est d\u00e9tenu depuis plus de vingt-deux ans. Dans ce cas, la taxe forfaitaire pr\u00e9vue \u00e0 <\/span><a href=\"https:\/\/www.legifrance.gouv.fr\/affichCodeArticle.do?cidTexte=LEGITEXT000006069577&amp;idArticle=LEGIARTI000006302813&amp;dateTexte=&amp;categorieLien=cid\" rel=\"noopener\"><span data-contrast=\"none\">l&rsquo;article 150 VI<\/span><\/a><span data-contrast=\"auto\"> n&rsquo;est pas due.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:660}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Loi n\u00b0 2013-1278 du 29 d\u00e9cembre 2013 de finances pour 2014, art. 19 III : Ces dispositions s&rsquo;appliquent aux cessions et aux exportations de biens r\u00e9alis\u00e9es \u00e0 compter du 1er janvier 2014.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:660}\">\u00a0<\/span><\/p><p><b><span data-contrast=\"auto\">ARTICLE 150 VM<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:660}\">\u00a0<\/span><\/p><p><span style=\"background-color: transparent; font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, 'Helvetica Neue', Arial, 'Noto Sans', sans-serif, 'Apple Color Emoji', 'Segoe UI Emoji', 'Segoe UI Symbol', 'Noto Color Emoji';\" data-contrast=\"auto\">I. Une d\u00e9claration, conforme \u00e0 un mod\u00e8le \u00e9tabli par l&rsquo;administration, retrace, selon le cas, les \u00e9l\u00e9ments servant \u00e0 la liquidation de la taxe ou l&rsquo;option pr\u00e9vue \u00e0 l&rsquo;article <\/span><a style=\"font-family: -apple-system, BlinkMacSystemFont, &#039;Segoe UI&#039;, Roboto, &#039;Helvetica Neue&#039;, Arial, &#039;Noto Sans&#039;, sans-serif, &#039;Apple Color Emoji&#039;, &#039;Segoe UI Emoji&#039;, &#039;Segoe UI Symbol&#039;, &#039;Noto Color Emoji&#039;;\" href=\"https:\/\/www.legifrance.gouv.fr\/affichCodeArticle.do?cidTexte=LEGITEXT000006069577&amp;idArticle=LEGIARTI000006302816&amp;dateTexte=&amp;categorieLien=cid\" rel=\"noopener\"><span data-contrast=\"none\">150 VL<\/span><\/a><span style=\"background-color: transparent; font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, 'Helvetica Neue', Arial, 'Noto Sans', sans-serif, 'Apple Color Emoji', 'Segoe UI Emoji', 'Segoe UI Symbol', 'Noto Color Emoji';\" data-contrast=\"auto\">. Elle est d\u00e9pos\u00e9e:<\/span><\/p><p><span data-contrast=\"auto\">1\u00b0 Pour les cessions r\u00e9alis\u00e9es avec la participation d&rsquo;un interm\u00e9diaire domicili\u00e9 fiscalement en France ou, en l&rsquo;absence d&rsquo;interm\u00e9diaire, lorsque l&rsquo;acqu\u00e9reur est un assujetti \u00e0 la taxe sur la valeur ajout\u00e9e \u00e9tabli en France, par cet interm\u00e9diaire ou cet acqu\u00e9reur, au service des imp\u00f4ts charg\u00e9 du recouvrement dont il d\u00e9pend ou, lorsqu&rsquo;il s&rsquo;agit d&rsquo;un officier minist\u00e9riel, au service des imp\u00f4ts charg\u00e9 du recouvrement comp\u00e9tent pour l&rsquo;enregistrement de l&rsquo;acte lorsqu&rsquo;il doit \u00eatre pr\u00e9sent\u00e9 \u00e0 cette formalit\u00e9, dans le d\u00e9lai pr\u00e9vu par l&rsquo;article <\/span><a href=\"https:\/\/www.legifrance.gouv.fr\/affichCodeArticle.do?cidTexte=LEGITEXT000006069577&amp;idArticle=LEGIARTI000006310183&amp;dateTexte=&amp;categorieLien=cid\" rel=\"noopener\"><span data-contrast=\"none\">635<\/span><\/a><span data-contrast=\"auto\">.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:660}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Toutefois, lorsqu&rsquo;il est assujetti \u00e0 la taxe sur la valeur ajout\u00e9e, l&rsquo;interm\u00e9diaire, l&rsquo;acqu\u00e9reur ou l&rsquo;officier minist\u00e9riel d\u00e9clare la taxe :<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:660}\">\u00a0<\/span><\/p><p><span style=\"background-color: transparent; font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, 'Helvetica Neue', Arial, 'Noto Sans', sans-serif, 'Apple Color Emoji', 'Segoe UI Emoji', 'Segoe UI Symbol', 'Noto Color Emoji';\" data-contrast=\"auto\">a) Sur l&rsquo;annexe \u00e0 la d\u00e9claration mentionn\u00e9e au 1 de l&rsquo;article <\/span><a style=\"font-family: -apple-system, BlinkMacSystemFont, &#039;Segoe UI&#039;, Roboto, &#039;Helvetica Neue&#039;, Arial, &#039;Noto Sans&#039;, sans-serif, &#039;Apple Color Emoji&#039;, &#039;Segoe UI Emoji&#039;, &#039;Segoe UI Symbol&#039;, &#039;Noto Color Emoji&#039;;\" href=\"https:\/\/www.legifrance.gouv.fr\/affichCodeArticle.do?cidTexte=LEGITEXT000006069577&amp;idArticle=LEGIARTI000006309527&amp;dateTexte=&amp;categorieLien=cid\" rel=\"noopener\"><span data-contrast=\"none\">287 <\/span><\/a><span style=\"background-color: transparent; font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, 'Helvetica Neue', Arial, 'Noto Sans', sans-serif, 'Apple Color Emoji', 'Segoe UI Emoji', 'Segoe UI Symbol', 'Noto Color Emoji';\" data-contrast=\"auto\">d\u00e9pos\u00e9e au titre du mois ou du trimestre au cours duquel l&rsquo;exigibilit\u00e9 de la taxe forfaitaire est intervenue s&rsquo;il est redevable de la taxe sur la valeur ajout\u00e9e et soumis au r\u00e9gime r\u00e9el normal d&rsquo;imposition ;<\/span><\/p><p><span style=\"background-color: transparent; font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, 'Helvetica Neue', Arial, 'Noto Sans', sans-serif, 'Apple Color Emoji', 'Segoe UI Emoji', 'Segoe UI Symbol', 'Noto Color Emoji';\" data-contrast=\"auto\">b) Sur la d\u00e9claration annuelle mentionn\u00e9e au 3 de l&rsquo;article 287 d\u00e9pos\u00e9e au titre de l&rsquo;exercice au cours duquel l&rsquo;exigibilit\u00e9 de la taxe forfaitaire est intervenue s&rsquo;il est redevable de la taxe sur la valeur ajout\u00e9e et soumis au r\u00e9gime simplifi\u00e9 d&rsquo;imposition pr\u00e9vu \u00e0 l&rsquo;article <\/span><a style=\"font-family: -apple-system, BlinkMacSystemFont, &#039;Segoe UI&#039;, Roboto, &#039;Helvetica Neue&#039;, Arial, &#039;Noto Sans&#039;, sans-serif, &#039;Apple Color Emoji&#039;, &#039;Segoe UI Emoji&#039;, &#039;Segoe UI Symbol&#039;, &#039;Noto Color Emoji&#039;;\" href=\"https:\/\/www.legifrance.gouv.fr\/affichCodeArticle.do?cidTexte=LEGITEXT000006069577&amp;idArticle=LEGIARTI000006309715&amp;dateTexte=&amp;categorieLien=cid\" rel=\"noopener\"><span data-contrast=\"none\">302 septies A<\/span><\/a><span style=\"background-color: transparent; font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, 'Helvetica Neue', Arial, 'Noto Sans', sans-serif, 'Apple Color Emoji', 'Segoe UI Emoji', 'Segoe UI Symbol', 'Noto Color Emoji';\" data-contrast=\"auto\"> ;<\/span><\/p><p><span style=\"background-color: transparent; font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, 'Helvetica Neue', Arial, 'Noto Sans', sans-serif, 'Apple Color Emoji', 'Segoe UI Emoji', 'Segoe UI Symbol', 'Noto Color Emoji';\">c) Sur l&rsquo;annexe \u00e0 la d\u00e9claration mentionn\u00e9e au 1 de l&rsquo;article 287 d\u00e9pos\u00e9e aupr\u00e8s du service charg\u00e9 du recouvrement dont rel\u00e8ve le principal \u00e9tablissement au plus tard le 25 du mois qui suit celui au cours duquel l&rsquo;exigibilit\u00e9 de la taxe forfaitaire est intervenue si l&rsquo;assujetti n&rsquo;est pas redevable de la taxe sur la valeur ajout\u00e9e.<\/span><\/p><p><span data-contrast=\"auto\">2\u00b0 Pour les exportations ou pour les cessions dans un pays tiers de biens export\u00e9s temporairement, par l&rsquo;exportateur \u00e0 la recette des douanes comp\u00e9tente pour cette exportation, lors de l&rsquo;accomplissement des formalit\u00e9s douani\u00e8res ;\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:660}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">3\u00b0 Pour les autres cessions, par le vendeur au service des imp\u00f4ts charg\u00e9 du recouvrement dont il rel\u00e8ve dans un d\u00e9lai d&rsquo;un mois \u00e0 compter de la cession.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:660}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">II. La taxe est acquitt\u00e9e lors du d\u00e9p\u00f4t de la d\u00e9claration.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:660}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">III. Le recouvrement de la taxe s&rsquo;op\u00e8re :<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:660}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">1\u00b0 Pour les cessions r\u00e9alis\u00e9es avec la participation d&rsquo;un interm\u00e9diaire ou, en l&rsquo;absence d&rsquo;interm\u00e9diaire, lorsque l&rsquo;acqu\u00e9reur est un assujetti \u00e0 la taxe sur la valeur ajout\u00e9e \u00e9tabli en France, selon les r\u00e8gles, garanties et sanctions pr\u00e9vues en mati\u00e8re de taxe sur le chiffre d&rsquo;affaires ;<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:660}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">2\u00b0 Pour les exportations et les cessions dans un pays tiers de biens export\u00e9s temporairement, selon les dispositions pr\u00e9vues par la l\u00e9gislation douani\u00e8re en vigueur ;<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:660}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">3\u00b0 Pour les autres cessions, selon les r\u00e8gles, garanties et sanctions pr\u00e9vues au titre IV du livre des proc\u00e9dures fiscales pour les imp\u00f4ts recouvr\u00e9s par les comptables publics comp\u00e9tents.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:660}\">\u00a0<\/span><\/p><p><span style=\"background-color: transparent; font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, 'Helvetica Neue', Arial, 'Noto Sans', sans-serif, 'Apple Color Emoji', 'Segoe UI Emoji', 'Segoe UI Symbol', 'Noto Color Emoji';\">IV. Les r\u00e9clamations sont pr\u00e9sent\u00e9es, instruites et jug\u00e9es comme en mati\u00e8re de taxes sur le chiffre d&rsquo;affaires si la taxe est recouvr\u00e9e par les comptables de la direction g\u00e9n\u00e9rale des finances publiques et comme en mati\u00e8re de douane si la taxe est recouvr\u00e9e par les receveurs des douanes.<\/span><\/p><div>\u00a0<\/div><p><span data-contrast=\"auto\">Conform\u00e9ment au II de l&rsquo;article 10 de l&rsquo;ordonnance n\u00b0 2015-681 du 18 juin 2015, les dispositions de l&rsquo;article 150 VM, dans leur r\u00e9daction issue de la pr\u00e9sente ordonnance, s&rsquo;appliquent aux d\u00e9clarations souscrites \u00e0 compter du 1er f\u00e9vrier 2016.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Informations fiscales importantes ESPACE GOLD CHANGE VOUS INFOMRE Fiscalit\u00e9 sur les m\u00e9taux pr\u00e9cieux La vente d\u2019or, d\u2019argent, de bijoux, de montres ou d\u2019objets de collection est soumise \u00e0 une fiscalit\u00e9 sp\u00e9cifique pr\u00e9vue par le Code g\u00e9n\u00e9ral des imp\u00f4ts (articles 150 VI \u00e0 150 VM).\u00a0 Deux r\u00e9gimes existent selon la situation du vendeur :\u00a0 LA TMP [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_theme","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4161","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/gap.espace-gold-change.com\/en\/wp-json\/wp\/v2\/pages\/4161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gap.espace-gold-change.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gap.espace-gold-change.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gap.espace-gold-change.com\/en\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/gap.espace-gold-change.com\/en\/wp-json\/wp\/v2\/comments?post=4161"}],"version-history":[{"count":4,"href":"https:\/\/gap.espace-gold-change.com\/en\/wp-json\/wp\/v2\/pages\/4161\/revisions"}],"predecessor-version":[{"id":4169,"href":"https:\/\/gap.espace-gold-change.com\/en\/wp-json\/wp\/v2\/pages\/4161\/revisions\/4169"}],"wp:attachment":[{"href":"https:\/\/gap.espace-gold-change.com\/en\/wp-json\/wp\/v2\/media?parent=4161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}